{"id":1372,"date":"2021-04-08T16:22:22","date_gmt":"2021-04-08T14:22:22","guid":{"rendered":"https:\/\/dolezalpartners.com\/?post_type=packages&#038;p=1372"},"modified":"2025-06-04T22:35:41","modified_gmt":"2025-06-04T20:35:41","slug":"korporatna-dokumentacia","status":"publish","type":"packages","link":"https:\/\/dolezalpartners.com\/sk\/pravni-balicky\/korporatna-dokumentacia\/","title":{"rendered":"Korpor\u00e1tna dokument\u00e1cia"},"content":{"rendered":"<div class=\"perex-img bg-light pb-5\">\n  <div class=\"container\">\n          <img decoding=\"async\" src=\"https:\/\/dolezalpartners.com\/wp-content\/uploads\/corporate-documentation.webp\" class=\"perex-img pb-5\" loading=\"lazy\" alt=\"\">\n        <div class=\"perex-description\"><p>Potrebujete zalo\u017ei\u0165 alebo zru\u0161i\u0165 spolo\u010dnos\u0165? Chcete zmeni\u0165 \u0161trukt\u00faru holdingu? Alebo spolo\u010dnos\u0165 preda\u0165? Vysvetl\u00edme cel\u00fd proces a priprav\u00edme dokument\u00e1ciu. A\u00a0e\u0161te V\u00e1m vopred povieme, ko\u013eko V\u00e1s to bude st\u00e1\u0165.<\/p>\n<p>Pr\u00e1vny bal\u00ed\u010dek korpor\u00e1tnej dokument\u00e1cie typicky zah\u0155\u0148a:<\/p>\n<ul>\n<li>Prerokovanie Va\u0161ich po\u017eiadaviek<\/li>\n<li>N\u00e1vrh \u0161trukt\u00fary transakcie<\/li>\n<li>Vypracovanie konkr\u00e9tnej korpor\u00e1tnej dokument\u00e1cie<\/li>\n<li>Post-transak\u010dn\u00fd servis<\/li>\n<\/ul>\n<\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<div id=\"kontakt\" class=\"contact-form-team\">\n  <div class=\"container\">\n    <div class=\"row\">\n              <div class=\"col-12 col-lg-4\">\n          <div class=\"contact-form-team__content\">\n                          <h2 class=\"contact-form-team__title\">Radi V\u00e1m pom\u00f4\u017eeme, kontaktujte n\u00e1s.<\/h2>\n                                      <div class=\"contact-form-team__perex\">\n                <p>Vypl\u0148te formul\u00e1r alebo n\u00e1s kontaktujte priamo.<\/p>\n\n              <\/div>\n                                                      <div class=\"contact-form-team__item\">\n                                    <div class=\"contact-form-team__item-image\">\n                                          <picture>\n          <source srcset=\"https:\/\/dolezalpartners.com\/wp-content\/cache\/image\/dolezalpartners-portret-161-edit-edit.webp\" type=\"image\/webp\">\n                <img decoding=\"async\" src=\"https:\/\/dolezalpartners.com\/wp-content\/uploads\/dolezalpartners-portret-161-edit-edit.jpg\" type=\"image\/jpeg\" width=\"1439\" height=\"1920\" alt=\"\" loading=\"lazy\" class=\"img-fluid\">\n  <\/picture>\n                                      <\/div>\n                  <div class=\"contact-form-team__item-content\">\n                                                              <h3 class=\"contact-form-team__item-title\">\n                        <a href=\"https:\/\/dolezalpartners.com\/sk\/nas-tym\/judr-ing-eva-mayerova\/\">JUDr. Ing. EVA MAYEROV\u00c1<\/a>\n                      <\/h3>\n                                                                                  <div class=\"contact-form-team__item-role\">\n                        Partner\n                      <\/div>\n                                                                                  <div class=\"contact-form-team__item-phone\">\n                        <a href=\"tel:+420543217520\">+420 543 217 520<\/a>\n                      <\/div>\n                                                                                  <div class=\"contact-form-team__item-email\">\n                        <a href=\"mailto:mayerova@dolezalpartners.com\">mayerova@dolezalpartners.com<\/a>\n                      <\/div>\n                                      <\/div>\n                <\/div>\n                              <div class=\"contact-form-team__item\">\n                                    <div class=\"contact-form-team__item-image\">\n                                          <picture>\n          <source srcset=\"https:\/\/dolezalpartners.com\/wp-content\/cache\/image\/dolezalpartners-portret-130-edit-edit-1.webp\" type=\"image\/webp\">\n                <img decoding=\"async\" src=\"https:\/\/dolezalpartners.com\/wp-content\/uploads\/dolezalpartners-portret-130-edit-edit-1.jpg\" type=\"image\/jpeg\" width=\"1439\" height=\"1920\" alt=\"\" loading=\"lazy\" class=\"img-fluid\">\n  <\/picture>\n                                      <\/div>\n                  <div class=\"contact-form-team__item-content\">\n                                                              <h3 class=\"contact-form-team__item-title\">\n                        <a href=\"https:\/\/dolezalpartners.com\/sk\/nas-tym\/mgr-petr-vrbka\/\">Mgr. PETR VRBKA<\/a>\n                      <\/h3>\n                                                                                  <div class=\"contact-form-team__item-role\">\n                        Associated partner\n                      <\/div>\n                                                                                  <div class=\"contact-form-team__item-phone\">\n                        <a href=\"tel:+420543217520\">+420 543 217 520<\/a>\n                      <\/div>\n                                                                                  <div class=\"contact-form-team__item-email\">\n                        <a href=\"mailto:vrbka@dolezalpartners.com\">vrbka@dolezalpartners.com<\/a>\n                      <\/div>\n                                      <\/div>\n                <\/div>\n                              <div class=\"contact-form-team__item\">\n                                    <div class=\"contact-form-team__item-image\">\n                                          <picture>\n          <source srcset=\"https:\/\/dolezalpartners.com\/wp-content\/cache\/image\/dolezalpartners-portret-050-edit-edit-1.webp\" type=\"image\/webp\">\n                <img decoding=\"async\" src=\"https:\/\/dolezalpartners.com\/wp-content\/uploads\/dolezalpartners-portret-050-edit-edit-1.jpg\" type=\"image\/jpeg\" width=\"1439\" height=\"1920\" alt=\"\" loading=\"lazy\" class=\"img-fluid\">\n  <\/picture>\n                                      <\/div>\n                  <div class=\"contact-form-team__item-content\">\n                                                              <h3 class=\"contact-form-team__item-title\">\n                        <a href=\"https:\/\/dolezalpartners.com\/sk\/nas-tym\/mgr-martin-winter\/\">Mgr. MARTIN WINTER<\/a>\n                      <\/h3>\n                                                                                  <div class=\"contact-form-team__item-role\">\n                        Partner\n                      <\/div>\n                                                                                  <div class=\"contact-form-team__item-phone\">\n                        <a href=\"tel:+420222544201\">+420 222 544 201<\/a>\n                      <\/div>\n                                                                                  <div class=\"contact-form-team__item-email\">\n                        <a href=\"mailto:winter@dolezalpartners.com\">winter@dolezalpartners.com<\/a>\n                      <\/div>\n                                      <\/div>\n                <\/div>\n                                    <\/div>\n        <\/div>\n      \n              <div class=\"col-12 col-lg-8\">\n          <div class=\"contact-form-team__form-wrapper wpform\"><style id=\"wpforms-css-vars-4731\">\n\t\t\t\t#wpforms-4731 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-4731\"><form id=\"wpforms-form-4731\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"4731\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/sk\/wp-json\/wp\/v2\/packages\/1372\" data-token=\"8d75362f07f66c1a08a2b52747ac14a0\" data-token-time=\"1784155675\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-4731-field_7-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"7\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-4731-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-4731-field_1\">Va\u0161e meno <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-4731-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-4731-field_1-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-4731-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-4731-field_2\">Spolo\u010dnos\u0165<\/label><input type=\"text\" id=\"wpforms-4731-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-4731-field_2-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-4731-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-4731-field_3\">Telef\u00f3n <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-4731-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-4731-field_3-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-4731-field_5-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-4731-field_5\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-4731-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" spellcheck=\"false\" aria-errormessage=\"wpforms-4731-field_5-error\" required><\/div><\/div><\/div><\/div><\/div>\t\t<div id=\"wpforms-4731-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-4731-field_4\" >Va\u0161e meno Spolo\u010dnos\u0165<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-4731-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-4731-field_6-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-4731-field_6\">Spr\u00e1va<\/label><textarea id=\"wpforms-4731-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-4731-field_6-error\" ><\/textarea><\/div><div id=\"wpforms-4731-field_8-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"8\"><div id=\"wpforms-4731-field_8\" class=\"wpforms-field-medium wpforms-field-row\" aria-errormessage=\"wpforms-4731-field_8-error\"><p>Odoslan\u00edm beriete na vedomie inform\u00e1cie o <a rel=\"noopener\" target=\"_blank\" href=\"\/sk\/informacie-o-spracuvani-osobnych-udajov\/\">sprac\u00favan\u00ed osobn\u00fdch \u00fadajov<\/a>.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-4731-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-4731-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-4731-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-turnstile\" ><div class=\"wpforms-turnstile\" data-sitekey=\"0x4AAAAAABAFvCe3xgPl2ojv\" data-action=\"FormID-4731\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-turnstile=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"4731\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/dolezalpartners.com\/sk\/wp-json\/wp\/v2\/packages\/1372\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-4731\" class=\"wpforms-submit btn btn-primary\" data-alt-text=\"Odosielanie...\" data-submit-text=\"Odosla\u0165 formul\u00e1r\" aria-live=\"assertive\" value=\"wpforms-submit\">Odosla\u0165 formul\u00e1r<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dolezalpartners.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1372","packages","type-packages","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/dolezalpartners.com\/sk\/wp-json\/wp\/v2\/packages\/1372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dolezalpartners.com\/sk\/wp-json\/wp\/v2\/packages"}],"about":[{"href":"https:\/\/dolezalpartners.com\/sk\/wp-json\/wp\/v2\/types\/packages"}],"wp:attachment":[{"href":"https:\/\/dolezalpartners.com\/sk\/wp-json\/wp\/v2\/media?parent=1372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}